{"id":12064,"date":"2026-04-13T07:30:08","date_gmt":"2026-04-13T07:30:08","guid":{"rendered":"https:\/\/sisula.it\/payments\/"},"modified":"2026-05-12T07:15:29","modified_gmt":"2026-05-12T07:15:29","slug":"payments","status":"publish","type":"page","link":"https:\/\/sisula.it\/en\/payments\/","title":{"rendered":"Payments"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12064\" class=\"elementor elementor-12064 elementor-10951\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9695d e-flex e-con-boxed e-con e-parent\" data-id=\"4d9695d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6808588 elementor-widget elementor-widget-heading\" data-id=\"6808588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pagamenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fcf9f5 e-flex e-con-boxed e-con e-parent\" data-id=\"9fcf9f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9219328 elementor-widget elementor-widget-heading\" data-id=\"9219328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pagamenti sicuri e flessibili<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b2dcf elementor-widget elementor-widget-text-editor\" data-id=\"56b2dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Su <b>S\u2019Isula<\/b>\u00a0puoi scegliere tra diversi metodi di pagamento, cos\u00ec da completare l\u2019acquisto nel modo pi\u00f9 comodo e sicuro. Durante il checkout vedrai sempre l\u2019<b>importo<\/b> <b>totale<\/b> (prodotti + eventuali costi di spedizione\/servizi) prima della conferma dell\u2019ordine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9722680 e-con-full e-flex e-con e-child\" data-id=\"9722680\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd62adb elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"bd62adb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #ffd600;\"><strong>In breve<\/strong><\/span><\/h3><h4><span style=\"color: #ffd600;\"><strong>Carta di credito\/debito<\/strong><\/span><\/h4><p><span style=\"color: #ffffff;\">Immediato, sicuro<\/span><br \/><span style=\"color: #ffffff;\">Ordine evaso dopo conferma pagamento<\/span><\/p><h4><span style=\"color: #ffd600;\"><strong>PayPal<\/strong><\/span><\/h4><p><span style=\"color: #ffffff;\">Immediato<\/span><br \/><span style=\"color: #ffffff;\">Possibilit\u00e0 di pagamento tramite account PayPal<\/span><\/p><h4><span style=\"color: #ffd600;\"><strong>Klarna<\/strong><\/span><\/h4><p><span style=\"color: #ffffff;\">Paga in modo flessibile, secondo le opzioni disponibili<\/span><br \/><span style=\"color: #ffffff;\">Ordine evaso dopo conferma pagamento<\/span><\/p><h4><span style=\"color: #ffd600;\"><strong>Bonifico bancario<\/strong><\/span><\/h4><p><span style=\"color: #ffffff;\">Ordine evaso dopo accredito<\/span><br \/><span style=\"color: #ffffff;\">Consigliato per aziende o importi importanti<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e15708 elementor-widget elementor-widget-text-editor\" data-id=\"9e15708\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Carta di credito\/debito<\/strong><\/h3><p>Accettiamo pagamenti tramite carta di credito o debito (circuiti disponibili in base al servizio di pagamento attivo sul Sito).<br \/>Il pagamento avviene tramite sistemi di pagamento sicuri: i dati della carta non vengono memorizzati sui nostri sistemi.<\/p><p><strong>Quando viene evaso l\u2019ordine?<\/strong><br \/>L\u2019ordine viene preso in carico ed evaso dopo la conferma dell\u2019esito del pagamento.<\/p><h3><strong>PayPal<\/strong><\/h3><p>Puoi pagare tramite PayPal, in modo rapido e sicuro.<br \/>Se hai un account PayPal, potrai completare il pagamento accedendo al tuo profilo.<\/p><p><strong>Quando viene evaso l\u2019ordine?<\/strong><br \/>L\u2019ordine viene preso in carico ed evaso dopo la conferma dell\u2019esito del pagamento.<\/p><h3><strong>Klarna<\/strong><\/h3><p>Puoi scegliere Klarna per un pagamento pi\u00f9 flessibile, in base alle opzioni disponibili al checkout (ad esempio: paga ora, paga dopo, pagamento a rate). La disponibilit\u00e0 delle opzioni e l\u2019eventuale possibilit\u00e0 di rateizzazione dipendono dalle condizioni applicate da Klarna e dall\u2019esito della procedura di autorizzazione.<\/p><p><strong>Quando viene evaso l\u2019ordine?<\/strong><br \/>L\u2019ordine viene preso in carico ed evaso dopo la conferma dell\u2019esito del pagamento.<\/p><h3><strong>Bonifico bancario<\/strong><\/h3><p>\u00c8 possibile pagare tramite bonifico bancario.<br \/>Una volta selezionata questa modalit\u00e0 al checkout, riceverai le istruzioni necessarie per effettuare il pagamento.<\/p><p><strong>Tempi di gestione<\/strong><br \/>L\u2019ordine sar\u00e0 evaso dopo la ricezione dell\u2019accredito, che pu\u00f2 richiedere alcuni giorni lavorativi in base ai tempi bancari.<\/p><p><strong>Consiglio pratico<\/strong><br \/>Per velocizzare la gestione, puoi indicare nella causale del bonifico: numero ordine e nome\/cognome (o ragione sociale)<\/p><h3><strong>Sicurezza dei pagamenti<\/strong><\/h3><p>Adottiamo misure tecniche e organizzative per rendere il processo di pagamento sicuro. In particolare:<\/p><ul><li>i pagamenti elettronici sono gestiti tramite provider specializzati;<\/li><li>non conserviamo i dati completi delle carte di pagamento;<\/li><li>in caso di anomalie o sospetti di frode, potremmo contattare il Cliente per verifiche o annullare l\u2019ordine a tutela di entrambe le parti.<\/li><\/ul><h3><strong>Fatturazione e dati fiscali<\/strong><\/h3><p>Se desideri fattura o documentazione fiscale corretta, assicurati di inserire in modo preciso:<\/p><ul><li>dati di intestazione,<\/li><li>indirizzo,<\/li><li>Codice Fiscale \/ Partita IVA (se richiesto),<\/li><li>eventuale PEC\/SDI (se previsto dal checkout o richiesto in fase di assistenza).<\/li><\/ul><h3>\u00a0<\/h3><h3><strong>Domande rapide<\/strong><\/h3><div class=\"TyagGW_tableContainer\"><div class=\"group TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\"><table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"3628\" data-end=\"4189\"><thead data-start=\"3628\" data-end=\"3650\"><tr data-start=\"3628\" data-end=\"3650\"><th class=\"\" data-start=\"3628\" data-end=\"3638\" data-col-size=\"md\">Domanda<\/th><th class=\"\" data-start=\"3638\" data-end=\"3650\" data-col-size=\"lg\">Risposta<\/th><\/tr><\/thead><tbody data-start=\"3661\" data-end=\"4189\"><tr data-start=\"3661\" data-end=\"3829\"><td data-start=\"3661\" data-end=\"3713\" data-col-size=\"md\">Posso cambiare metodo di pagamento dopo l\u2019ordine?<\/td><td data-col-size=\"lg\" data-start=\"3713\" data-end=\"3829\">Dipende dallo stato dell\u2019ordine. Contattaci subito e faremo il possibile se non \u00e8 gi\u00e0 in lavorazione\/spedizione.<\/td><\/tr><tr data-start=\"3830\" data-end=\"3967\"><td data-start=\"3830\" data-end=\"3865\" data-col-size=\"md\">Il pagamento con carta \u00e8 sicuro?<\/td><td data-col-size=\"lg\" data-start=\"3865\" data-end=\"3967\">S\u00ec: avviene tramite provider specializzati e i dati carta non sono memorizzati sui nostri sistemi.<\/td><\/tr><tr data-start=\"3968\" data-end=\"4053\"><td data-start=\"3968\" data-end=\"4011\" data-col-size=\"md\">Quando parte la spedizione con bonifico?<\/td><td data-start=\"4011\" data-end=\"4053\" data-col-size=\"lg\">Dopo accredito effettivo del bonifico.<\/td><\/tr><\/tbody><\/table><\/div><\/div><h3>\u00a0<\/h3><h3><strong>Contatti<\/strong><\/h3><p>Per supporto su pagamenti e ordini:<br \/><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"mailto:sisula@sisula.it\"><strong>sisula@sisula.it<\/strong><\/a><\/span><br \/><strong>+39 070 860 7626<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b62c84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b62c84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-954454b\" data-id=\"954454b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54bb329 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"54bb329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"60\" viewBox=\"0 0 60 60\" fill=\"none\"><path d=\"M51.9255 21.6447H40.5362L37.266 10.8191C36.7021 9.12766 35.1234 8 33.4319 8C33.0936 8 32.6426 8.11277 32.3043 8.22553L6.81915 16.0064C5.12766 16.4574 4 18.0362 4 19.7277C4 20.066 4.11277 20.517 4.22553 20.8553L9.18723 36.8681C9.75106 38.5596 11.3298 39.6872 13.0213 39.6872C13.2468 39.6872 13.5851 39.6872 13.8106 39.5745V47.6936C13.8106 49.8362 15.6149 51.6404 17.7574 51.6404H52.1511C54.2936 51.6404 56.0979 49.8362 56.0979 47.6936V25.5915C55.9851 23.3362 54.1809 21.6447 51.9255 21.6447ZM54.8574 47.8064C54.8574 49.3851 53.617 50.6255 52.0383 50.6255H17.6447C16.066 50.6255 14.8255 49.3851 14.8255 47.8064V39.3489V38.2213V29.5383V28.4106V26.1553V25.5915C14.8255 25.366 14.8255 25.1404 14.9383 24.9149C15.0511 24.4638 15.2766 24.0128 15.6149 23.6745L16.6298 24.4638L17.7574 25.2532L19.9 26.8319L21.0277 27.6213L29.4851 33.7106L30.6128 34.5L33.3191 36.417C33.7702 36.7553 34.2213 36.8681 34.6723 36.8681C35.1234 36.8681 35.5745 36.7553 36.0255 36.417L53.9553 23.6745C54.4064 24.1255 54.7447 24.8021 54.7447 25.5915V47.8064H54.8574ZM51.9255 22.7723C52.3766 22.7723 52.7149 22.8851 53.0532 22.9979L35.4617 35.5149C35.2362 35.6277 35.0106 35.7404 34.7851 35.7404C34.5596 35.7404 34.334 35.6277 34.1085 35.5149L32.0787 34.0489L30.9511 33.2596L22.3809 27.1702L21.2532 26.3809L19.1106 24.8021L17.983 24.0128L16.517 22.9979C16.8553 22.8851 17.1936 22.7723 17.6447 22.7723H22.0426H25.8766H33.0936H36.8149H39.634H40.7617H51.9255ZM12.9085 38.6723C11.6681 38.6723 10.5404 37.883 10.2021 36.6426L5.24043 20.6298C5.12766 20.2915 5.12766 20.066 5.12766 19.7277C5.12766 18.6 5.91702 17.4723 7.15745 17.0213L32.6426 9.24043C32.8681 9.12766 33.0936 9.12766 33.4319 9.12766C34.6723 9.12766 35.8 9.91702 36.1383 11.1574L39.2957 21.6447H29.4851L35.6872 19.7277C36.0255 19.6149 36.1383 19.2766 36.0255 19.0511C35.9128 18.7128 35.5745 18.6 35.3489 18.7128L25.5383 21.7574H18.3213L34.6723 16.7957C35.0106 16.683 35.1234 16.3447 35.0106 16.1191C34.8979 15.7809 34.5596 15.6681 34.334 15.7809L9.07447 23.3362C8.73617 23.4489 8.6234 23.7872 8.73617 24.0128C8.84894 24.3511 9.18723 24.4638 9.41277 24.3511L14.8255 22.6596C14.1489 23.3362 13.6979 24.2383 13.5851 25.2532L9.86383 26.3809C9.52553 26.4936 9.41277 26.8319 9.52553 27.0574C9.6383 27.3957 9.9766 27.5085 10.2021 27.3957L13.4723 26.3809V28.6362L10.766 29.4255C10.4277 29.5383 10.3149 29.8766 10.4277 30.1021C10.6532 30.5532 10.9915 30.666 11.3298 30.5532L13.6979 29.8766V38.5596C13.3596 38.5596 13.134 38.6723 12.9085 38.6723Z\" fill=\"currentColor\"><\/path><path d=\"M34.2212 12.7362C34.1085 12.3979 33.7702 12.2851 33.5446 12.3979L8.05954 20.1787C7.72124 20.2915 7.60848 20.6298 7.72124 20.8553C7.83401 21.1936 8.17231 21.3064 8.39784 21.1936L33.8829 13.4128C34.2212 13.3 34.334 13.0745 34.2212 12.7362Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHai una richiesta speciale?<br>Contattaci subito\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a65b204\" data-id=\"a65b204\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b3f501 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5b3f501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"60\" viewBox=\"0 0 60 60\" fill=\"none\"><path d=\"M12.9085 38.6723C11.6681 38.6723 10.5404 37.883 10.2021 36.6426L7.04468 26.3809L6.48085 26.4936L5.24043 22.5468L5.80426 22.434L5.24043 20.6298C5.12766 20.2915 5.12766 20.066 5.12766 19.7277C5.12766 18.6 5.91702 17.4723 7.15745 17.0213L32.6426 9.24043C32.8681 9.12766 33.0936 9.12766 33.4319 9.12766C34.6723 9.12766 35.8 9.91702 36.1383 11.1574L36.7021 12.9617L37.266 12.8489L38.5064 16.7957L37.9426 16.9085L39.183 21.0809H40.3106L37.1532 10.8191C36.7021 9.12766 35.1234 8 33.4319 8C33.0936 8 32.6426 8.11277 32.3043 8.22553L6.81915 16.0064C5.12766 16.4574 4 18.0362 4 19.7277C4 20.066 4.11277 20.517 4.22553 20.8553L9.18723 36.8681C9.75106 38.5596 11.3298 39.6872 13.0213 39.6872C13.2468 39.6872 13.5851 39.6872 13.8106 39.5745V38.4468C13.3596 38.5596 13.134 38.6723 12.9085 38.6723Z\" fill=\"currentColor\"><\/path><path d=\"M38.3937 16.7957L37.1532 12.8489L36.7022 12.9616L5.80431 22.434L5.24048 22.5467L6.4809 26.4936L7.04473 26.3808L13.6979 24.351C14.0362 22.5468 15.6149 21.0808 17.532 21.0808H24.2979L37.8298 16.9085L38.3937 16.7957Z\" fill=\"currentColor\"><\/path><path d=\"M51.9255 21.0808H40.3106H39.183H24.4106H17.6447C15.7277 21.0808 14.0362 22.5468 13.8106 24.351C13.8106 24.5766 13.6979 24.8021 13.6979 25.0276V38.5595V39.6872V47.2425C13.6979 49.3851 15.5021 51.1893 17.6447 51.1893H52.0383C54.1809 51.1893 55.9851 49.3851 55.9851 47.2425V25.0276C55.9851 22.8851 54.1809 21.0808 51.9255 21.0808ZM54.8575 47.2425C54.8575 48.8212 53.617 50.0617 52.0383 50.0617H17.6447C16.066 50.0617 14.8255 48.8212 14.8255 47.2425V25.0276C14.8255 23.4489 16.066 22.2085 17.6447 22.2085H52.0383C53.617 22.2085 54.8575 23.4489 54.8575 25.0276V47.2425Z\" fill=\"currentColor\"><\/path><path d=\"M23.8468 33.7107C25.4255 33.5979 26.8915 32.132 26.8915 30.666C26.7787 29.3128 25.3128 27.8469 23.8468 27.6213C22.3808 27.5086 20.9149 28.9745 20.8021 30.666C20.8021 32.3575 22.2681 33.8235 23.8468 33.7107Z\" fill=\"currentColor\"><\/path><path d=\"M39.8596 39.6873H21.4787C21.1404 39.6873 20.8021 40.0256 20.8021 40.3639V40.5894C20.8021 40.9277 21.1404 41.266 21.4787 41.266H39.8596C40.1979 41.266 40.5362 40.9277 40.5362 40.5894V40.3639C40.6489 40.0256 40.3106 39.6873 39.8596 39.6873Z\" fill=\"currentColor\"><\/path><path d=\"M26.4404 43.183H21.4787C21.1404 43.183 20.8021 43.5213 20.8021 43.8596V44.0851C20.8021 44.4234 21.1404 44.7617 21.4787 44.7617H26.4404C26.7787 44.7617 27.117 44.4234 27.117 44.0851V43.8596C27.117 43.5213 26.8915 43.183 26.4404 43.183Z\" fill=\"currentColor\"><\/path><path d=\"M48.0915 39.6873H43.3553C43.017 39.6873 42.6787 40.0256 42.6787 40.3639V40.5894C42.6787 40.9277 43.017 41.266 43.3553 41.266H48.0915C48.4298 41.266 48.7681 40.9277 48.7681 40.5894V40.3639C48.7681 40.0256 48.4298 39.6873 48.0915 39.6873Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPagamenti sicuri <br>con carta di credito\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-76449e8\" data-id=\"76449e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9cc345 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c9cc345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"60\" viewBox=\"0 0 60 60\" fill=\"none\"><path d=\"M37.59 13.38L38.855 17.52H40.005L38.395 12L20.225 17.52H24.135L37.59 13.38Z\" fill=\"currentColor\"><\/path><path d=\"M48.975 36.955V44.2C48.975 45.81 47.71 47.075 46.1 47.075H11.025C9.415 47.19 8.15 45.81 8.15 44.2V21.66C8.15 20.05 9.415 18.67 11.025 18.67H46.1C47.71 18.67 48.975 19.935 48.975 21.545V28.79C49.32 28.79 49.78 28.905 50.125 29.02V21.66C50.125 19.475 48.285 17.635 46.1 17.635H40.12H38.97H24.135H20.225H11.025C8.84 17.52 7 19.36 7 21.66V44.2C7 46.385 8.84 48.225 11.025 48.225H46.1C48.285 48.225 50.125 46.385 50.125 44.2V36.725C49.78 36.84 49.32 36.955 48.975 36.955Z\" fill=\"currentColor\"><\/path><path d=\"M53.0001 32.93C53.0001 31.09 51.7351 29.595 50.1251 29.135C49.7801 29.02 49.4351 28.905 48.9751 28.905H36.2101C34.0251 28.905 32.1851 30.745 32.1851 32.93C32.1851 35.115 34.0251 36.955 36.2101 36.955H48.9751C49.3201 36.955 49.7801 36.84 50.1251 36.725C51.7351 36.265 53.0001 34.77 53.0001 32.93ZM36.2101 35.805C34.6001 35.805 33.3351 34.54 33.3351 32.93C33.3351 31.32 34.6001 30.055 36.2101 30.055H48.9751C50.5851 30.055 51.8501 31.32 51.8501 32.93C51.8501 34.54 50.5851 35.805 48.9751 35.805H36.2101Z\" fill=\"currentColor\"><\/path><path d=\"M36.555 31.78C35.98 31.78 35.405 32.24 35.405 32.93C35.405 33.505 35.98 34.08 36.555 34.08C37.13 33.965 37.705 33.505 37.705 32.93C37.705 32.355 37.13 31.895 36.555 31.78Z\" fill=\"currentColor\"><\/path><path d=\"M12.06 22.8101C11.715 22.8101 11.485 23.0401 11.485 23.3851V26.0301C11.485 26.3751 11.715 26.6051 12.06 26.6051C12.405 26.6051 12.635 26.3751 12.635 26.0301V23.3851C12.635 23.0401 12.405 22.8101 12.06 22.8101Z\" fill=\"currentColor\"><\/path><path d=\"M12.06 28.33C11.715 28.33 11.485 28.56 11.485 28.905V31.55C11.485 31.895 11.715 32.125 12.06 32.125C12.405 32.125 12.635 31.895 12.635 31.55V28.905C12.635 28.56 12.405 28.33 12.06 28.33Z\" fill=\"currentColor\"><\/path><path d=\"M12.06 33.735C11.715 33.735 11.485 33.965 11.485 34.31V36.955C11.485 37.3 11.715 37.53 12.06 37.53C12.405 37.53 12.635 37.3 12.635 36.955V34.31C12.635 34.08 12.405 33.735 12.06 33.735Z\" fill=\"currentColor\"><\/path><path d=\"M12.06 39.255C11.715 39.255 11.485 39.485 11.485 39.83V42.475C11.485 42.82 11.715 43.05 12.06 43.05C12.405 43.05 12.635 42.82 12.635 42.475V39.83C12.635 39.485 12.405 39.255 12.06 39.255Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSpedizione gratuita per <br>ordini superiori a 79\u20ac\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d86248f\" data-id=\"d86248f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76d800 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f76d800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"60\" viewBox=\"0 0 60 60\" fill=\"none\"><path d=\"M50.2568 29.7784C50.2568 29.0811 49.5595 28.2676 48.746 28.2676V31.4054C49.4433 31.2892 50.1406 30.5919 50.2568 29.7784Z\" fill=\"currentColor\"><\/path><path d=\"M29.6865 49.3027L36.8919 34.6595H48.8622C51.5352 34.6595 53.7433 32.4514 53.7433 29.7784C53.7433 27.1054 51.5352 24.8973 48.8622 24.8973L36.8919 24.8973L29.6865 10.3703C29.2217 9.32437 28.2919 8.74329 27.1298 8.74329H24.573C23.4109 8.74329 22.4811 9.67302 22.4811 10.8352C22.4811 11.0676 22.4811 11.3 22.5973 11.4163L26.7811 24.8973L19.2271 24.8973L16.3217 21.5271C15.5081 20.5973 14.346 20.0163 13.0676 20.0163H9.58112C8.76761 20.0163 8.18653 20.7136 8.18653 21.4109C8.18653 21.6433 8.18653 21.7595 8.30275 21.9919L11.673 29.6622L8.30275 37.3325C8.18653 37.5649 8.18653 37.6811 8.18653 37.9136C8.18653 38.6109 8.76761 39.3082 9.58112 39.3082H13.0676C14.346 39.3082 15.5081 38.7271 16.3217 37.7973L19.2271 34.4271L26.7811 34.4271L22.5973 48.2568C22.4811 48.4892 22.4811 48.7217 22.4811 48.8379C22.4811 50 23.4109 50.9298 24.573 50.9298H27.1298C28.2919 50.9298 29.2217 50.2325 29.6865 49.3027ZM24.573 49.7676C24.3406 49.7676 24.1082 49.6514 23.8757 49.5352C23.7595 49.419 23.6433 49.1865 23.6433 48.9541V48.7217L28.2919 33.7298L18.646 33.7298L15.3919 37.4487C14.8109 38.146 13.9973 38.4946 13.0676 38.4946H9.58112L9.46491 38.3784L9.34869 38.2622V38.146L12.9514 30.0109L12.8352 29.7784L9.34869 21.8757V21.7595L9.46491 21.6433L9.58112 21.5271H13.0676C13.9973 21.5271 14.8109 21.8757 15.3919 22.573L18.646 26.2919L28.2919 26.2919L23.7595 11.0676V10.8352C23.7595 10.6027 23.8757 10.3703 23.9919 10.2541C24.1082 10.0217 24.3406 9.90545 24.573 9.90545H27.1298C27.7109 9.90545 28.2919 10.2541 28.6406 10.8352L36.0784 26.0595L48.8622 26.0595C50.9541 26.0595 52.5811 27.6865 52.5811 29.7784C52.5811 31.8703 50.9541 33.4973 48.8622 33.4973H36.0784L28.6406 48.7217C28.4081 49.3027 27.8271 49.6514 27.1298 49.6514H24.573V49.7676Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSiamo in grado di spedire <br>in tutto il mondo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-12064","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/pages\/12064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/comments?post=12064"}],"version-history":[{"count":1,"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/pages\/12064\/revisions"}],"predecessor-version":[{"id":12564,"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/pages\/12064\/revisions\/12564"}],"wp:attachment":[{"href":"https:\/\/sisula.it\/en\/wp-json\/wp\/v2\/media?parent=12064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}